






{"id":93,"count":1,"description":"","link":"https:\/\/calakmul.com.mx\/en\/tag\/santa-fe-cdmx\/","name":"Santa Fe CDMX","slug":"santa-fe-cdmx","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Fe CDMX archivos - Calakmul<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Fe CDMX archivos - Calakmul\" \/>\n<meta property=\"og:url\" content=\"https:\/\/calakmul.com.mx\/en\/tag\/santa-fe-cdmx\/\" \/>\n<meta property=\"og:site_name\" content=\"Calakmul\" \/>\n<meta property=\"og:image\" content=\"https:\/\/calakmul.com.mx\/wp-content\/uploads\/2025\/06\/logo-seo-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/tag\\\/santa-fe-cdmx\\\/\",\"url\":\"https:\\\/\\\/calakmul.com.mx\\\/tag\\\/santa-fe-cdmx\\\/\",\"name\":\"Santa Fe CDMX archivos - Calakmul\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/tag\\\/santa-fe-cdmx\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/tag\\\/santa-fe-cdmx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/calakmul.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Fe CDMX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/calakmul.com.mx\\\/\",\"name\":\"Calakmul\",\"description\":\"Calakmul\u00ae, Arte como Arquitectura\",\"publisher\":{\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#organization\"},\"alternateName\":\"Calakmul\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/calakmul.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#organization\",\"name\":\"Calakmul\",\"alternateName\":\"Calakmul\",\"url\":\"https:\\\/\\\/calakmul.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Calakmul\"},\"image\":{\"@id\":\"https:\\\/\\\/calakmul.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/calakmularteyarquitectura\",\"https:\\\/\\\/www.instagram.com\\\/calakmul_arte_y_arquitectura\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/calakmul-arte-y-arquitectura\\\/?originalSubdomain=mx\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Fe CDMX archivos - Calakmul","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Santa Fe CDMX archivos - Calakmul","og_url":"https:\/\/calakmul.com.mx\/en\/tag\/santa-fe-cdmx\/","og_site_name":"Calakmul","og_image":[{"width":1104,"height":580,"url":"https:\/\/calakmul.com.mx\/wp-content\/uploads\/2025\/06\/logo-seo-.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/calakmul.com.mx\/tag\/santa-fe-cdmx\/","url":"https:\/\/calakmul.com.mx\/tag\/santa-fe-cdmx\/","name":"Santa Fe CDMX archivos - Calakmul","isPartOf":{"@id":"https:\/\/calakmul.com.mx\/#website"},"breadcrumb":{"@id":"https:\/\/calakmul.com.mx\/tag\/santa-fe-cdmx\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/calakmul.com.mx\/tag\/santa-fe-cdmx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/calakmul.com.mx\/"},{"@type":"ListItem","position":2,"name":"Santa Fe CDMX"}]},{"@type":"WebSite","@id":"https:\/\/calakmul.com.mx\/#website","url":"https:\/\/calakmul.com.mx\/","name":"Calakmul","description":"Calakmul\u00ae, Arte como Arquitectura","publisher":{"@id":"https:\/\/calakmul.com.mx\/#organization"},"alternateName":"Calakmul","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/calakmul.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/calakmul.com.mx\/#organization","name":"Calakmul","alternateName":"Calakmul","url":"https:\/\/calakmul.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/calakmul.com.mx\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Calakmul"},"image":{"@id":"https:\/\/calakmul.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/calakmularteyarquitectura","https:\/\/www.instagram.com\/calakmul_arte_y_arquitectura\/","https:\/\/www.linkedin.com\/company\/calakmul-arte-y-arquitectura\/?originalSubdomain=mx"]}]}},"_links":{"self":[{"href":"https:\/\/calakmul.com.mx\/en\/wp-json\/wp\/v2\/tags\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calakmul.com.mx\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/calakmul.com.mx\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/calakmul.com.mx\/en\/wp-json\/wp\/v2\/posts?tags=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}